{"id":766,"date":"2019-11-19T16:50:38","date_gmt":"2019-11-19T15:50:38","guid":{"rendered":"https:\/\/www.heartengland.co.uk\/school\/"},"modified":"2019-11-29T16:08:15","modified_gmt":"2019-11-29T15:08:15","slug":"school","status":"publish","type":"page","link":"https:\/\/www.jostudyenglishacademy.com\/es\/school\/","title":{"rendered":"School"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"766\" class=\"elementor elementor-766\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72eafb04 elementor-section-stretched elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"72eafb04\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7a4d812f\" data-id=\"7a4d812f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2587e213 elementor-widget elementor-widget-heading\" data-id=\"2587e213\" data-element_type=\"widget\" id=\"form\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>Scuola<\/b><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3352208f elementor-section-stretched bottom-0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3352208f\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3a85e6f7\" data-id=\"3a85e6f7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-414f69a2 bottom-0 elementor-widget elementor-widget-text-editor\" data-id=\"414f69a2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Stai cercando un corso di inglese per bambini nel Regno Unito?<\/h2><h4>Puoi scegliere un corso di inglese per bambini tra i tanti che possiamo offrire. I programmi di gruppo e in singola sono per studenti di et\u00e0 compresa tra 5 e 17 anni e gruppi scolastici per bambini tra 12 e 17 anni.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6a6e5ea3\" data-id=\"6a6e5ea3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63602d2a bottom-0 elementor-widget elementor-widget-text-editor\" data-id=\"63602d2a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The Heart of England Study Programs \u00e8 un\u2019azienda a conduzione familiare e consociata della Heart of England Language School (scuola per adulti).<\/p><p>Il nostro obiettivo \u00e8 fornire corsi di lingua inglese di alta qualit\u00e0 e gestiti con cura. Abbiamo offerto corsi creativi e stimolanti dal 1993 e molti dei nostri studenti tornano ancora, cos\u00ec, come \u00e8 immaginabile, i nostri corsi di inglese per bambini hanno punteggi di soddisfazione elevati; consulta i nostri opuscoli per maggiori dettagli.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e330ac6 elementor-section-stretched bottom-0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e330ac6\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2ce7ae9\" data-id=\"2ce7ae9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eefd841 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"eefd841\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositivas\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-32e3c98 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Heart_of_england\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-5a32039 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"MINISTAY-HOE\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-e8b39d8 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"MINISTAY-HOE-2\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositiva anterior\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositiva siguiente\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-81db619\" data-id=\"81db619\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9ed226 bottom-0 elementor-widget elementor-widget-text-editor\" data-id=\"d9ed226\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Corsi di inglese per bambini The Heart of England:<\/h3><ol><li>Corsi che incentivano l\u2019interesse per la lingua;<\/li><li>Corsi divertenti e stimolanti oltre che educativi;<\/li><li>Corsi in esterna e supporto per le attivit\u00e0 pomeridiane;<\/li><li>Corsi che coinvolgono tutte e 4 le abilit\u00e0 in un programma equilibrato ma si concentrano maggiormente sul parlare e ascoltare;<\/li><li>Corsi che rendono l\u2019apprendimento della lingua divertente attraverso lezioni fantasiose e ben strutturate;<\/li><li>Gamma di metodologie comprovate e tecniche di insegnamento selezionate;<\/li><li>I corsi sono progettati per soddisfare le persone con diversi stili o esigenze di apprendimento della lingua inglese.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0b65779 elementor-section-stretched bottom-0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0b65779\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6064aa9\" data-id=\"6064aa9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ad27d0 bottom-0 elementor-widget elementor-widget-text-editor\" data-id=\"0ad27d0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Perch\u00e9 scegliere un corso di inglese per bambini della scuola The Heart of England. Leamington Spa offre:<\/strong><\/h4><ol><li>Un luogo accogliente e confortevole per studiare. I nostri ospiti sono molto apprezzati dai nostri studenti e Leamington Spa \u00e8 stata votata \u201cil luogo pi\u00f9 felice dove soggiornare\u201d dal quotidiano The Independent;<\/li><li>Un ambiente sicuro. I nostri studenti si sentono sicuri e a casa dal momento in cui arrivano e noi li supportiamo durante tutto il loro soggiorno per renderlo un\u2019esperienza positiva e piacevole;<\/li><li>Posizione facilmente accessibile. Siamo a breve distanza da molte belle citt\u00e0, collegamenti efficienti sia in treno, sia in auto o in aereo;<\/li><li>Bellissimi parchi e giardini. Un\u2019ampia variet\u00e0 di spazi esterni attraversa il centro citt\u00e0 offrendo luoghi per rilassarsi e incontrarsi;<\/li><li>Una citt\u00e0 facile da visitare. I nostri studenti possono conoscere rapidamente la citt\u00e0 e diventare indipendenti in pochissimo tempo;<\/li><li>L\u2019area \u00e8 ricca di storia, luoghi di interesse e strutture sportive. Offriamo oltre 40 attivit\u00e0 diverse a casa nostra durante il Campo Estivo;<\/li><li>Agevole collegamento con <a href=\"http:\/\/www.visitwarwick.co.uk\">Warwick<\/a>, <a href=\"http:\/\/www.visitstratforduponavon.co.uk\">Stratford-upon-Avon<\/a>, <a href=\"http:\/\/www.visitbirmingham.com\">Birmingham<\/a>, <a href=\"http:\/\/www.oxfordcityguide.com\">Oxford<\/a> e <a href=\"http:\/\/www.visitlondon.com\">Londra<\/a>.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-670eaed\" data-id=\"670eaed\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e461aaf elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"e461aaf\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositivas\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-32e3c98 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"MINISTAY-HOE-3\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-5a32039 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"ONE-TO-ONE-HOE\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositiva anterior\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositiva siguiente\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c5c4c96 elementor-section-stretched bottom-0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c5c4c96\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4b632ed\" data-id=\"4b632ed\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22778d5 bottom-0 elementor-widget elementor-widget-text-editor\" data-id=\"22778d5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Vuoi imparare o migliorare il tuo inglese comodamente da casa?<\/strong><\/h4><h4>Scegli un corso di lingua inglese online, con insegnanti madrelingua, personalizzato per te!<\/h4><p>Gli insegnanti \u201cLesson Live\u201d, connessi da tutte le parti del mondo, <strong>sono sempre madrelingua e\u00a0certificati IELTS\u00a0o\u00a0CELTA.<\/strong><br \/><strong><br \/><\/strong><a href=\"https:\/\/www.lessonlive.it\/\" target=\"_blank\" rel=\"noopener\">Inizia il tuo percorso in Lesson Live<\/a> scoprendo il tuo livello di inglese <br \/><strong>in modo semplice e gratuito!<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0e22f2c\" data-id=\"0e22f2c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-363d901 elementor-widget elementor-widget-image\" data-id=\"363d901\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.lessonlive.it\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"662\" src=\"https:\/\/www.jostudyenglishacademy.com\/wp-content\/uploads\/2019\/11\/Lesson-Live-2-1-OK.png\" class=\"attachment-large size-large wp-image-866\" alt=\"\" srcset=\"https:\/\/www.jostudyenglishacademy.com\/wp-content\/uploads\/2019\/11\/Lesson-Live-2-1-OK.png 1000w, https:\/\/www.jostudyenglishacademy.com\/wp-content\/uploads\/2019\/11\/Lesson-Live-2-1-OK-300x199.png 300w, https:\/\/www.jostudyenglishacademy.com\/wp-content\/uploads\/2019\/11\/Lesson-Live-2-1-OK-768x508.png 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f48a560 elementor-section-stretched bottom-0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f48a560\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b4f2da7\" data-id=\"b4f2da7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c3179c6 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"c3179c6\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositivas\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-32e3c98 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Heart_of_england\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-5a32039 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"MINISTAY-HOE\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-e8b39d8 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"MINISTAY-HOE-2\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositiva anterior\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositiva siguiente\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6647520\" data-id=\"6647520\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-710aa08 bottom-0 elementor-widget elementor-widget-text-editor\" data-id=\"710aa08\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Parlano di noi<\/h3><p>I programmi di studio Heart of England sono gestiti dal marito e moglie Andrew Bain e Louisa Enock. Siamo una scuola di lingue a conduzione familiare, che opera dal 1993 a Leamington Spa. Louisa Enock \u00e8 la direttrice degli studi e si \u00e8 qualificata nel 2008. Siamo accreditati tramite ABLS.<\/p><p>Offriamo lezioni di lingua inglese e visite culturali per relatori di altre lingue di tutte le et\u00e0, con il duplice scopo di migliorare le competenze linguistiche degli studenti e allo stesso tempo offrire loro l\u2019esperienza culturale di vivere in Inghilterra con una famiglia ospitante.<\/p><p>Vogliamo che i nostri studenti si sentano sicuri e benvenuti nel loro nuovo ambiente. Essendo genitori noi stessi capiamo che questo pu\u00f2 essere un momento preoccupante per genitori e studenti. Offriamo supporto personalizzato 24 ore su 24, 7 giorni su 7, un ambiente di cura e un servizio professionale con padroni di casa di qualit\u00e0, lezioni ed escursioni varie ed emozionanti.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-504a0828 elementor-section-stretched elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"504a0828\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cdcafa0\" data-id=\"cdcafa0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31d3ca1c elementor-widget elementor-widget-text-editor\" data-id=\"31d3ca1c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Sei interessato ai nostri corsi?<\/h3><h5>Se hai qualche richiesta specifica saremo felici di risponderti.<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4bcf22ca\" data-id=\"4bcf22ca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57bce448 elementor-align-right button-icon elementor-widget elementor-widget-button\" data-id=\"57bce448\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/?page_id=140\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-envelope-open\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M494.586 164.516c-4.697-3.883-111.723-89.95-135.251-108.657C337.231 38.191 299.437 0 256 0c-43.205 0-80.636 37.717-103.335 55.859-24.463 19.45-131.07 105.195-135.15 108.549A48.004 48.004 0 0 0 0 201.485V464c0 26.51 21.49 48 48 48h416c26.51 0 48-21.49 48-48V201.509a48 48 0 0 0-17.414-36.993zM464 458a6 6 0 0 1-6 6H54a6 6 0 0 1-6-6V204.347c0-1.813.816-3.526 2.226-4.665 15.87-12.814 108.793-87.554 132.364-106.293C200.755 78.88 232.398 48 256 48c23.693 0 55.857 31.369 73.41 45.389 23.573 18.741 116.503 93.493 132.366 106.316a5.99 5.99 0 0 1 2.224 4.663V458zm-31.991-187.704c4.249 5.159 3.465 12.795-1.745 16.981-28.975 23.283-59.274 47.597-70.929 56.863C336.636 362.283 299.205 400 256 400c-43.452 0-81.287-38.237-103.335-55.86-11.279-8.967-41.744-33.413-70.927-56.865-5.21-4.187-5.993-11.822-1.745-16.981l15.258-18.528c4.178-5.073 11.657-5.843 16.779-1.726 28.618 23.001 58.566 47.035 70.56 56.571C200.143 320.631 232.307 352 256 352c23.602 0 55.246-30.88 73.41-45.389 11.994-9.535 41.944-33.57 70.563-56.568 5.122-4.116 12.601-3.346 16.778 1.727l15.258 18.526z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contattaci<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Scuola Stai cercando un corso di inglese per bambini nel Regno Unito? Puoi scegliere un corso di inglese per bambini tra i tanti che possiamo offrire. I programmi di gruppo e in singola sono per studenti di et\u00e0 compresa tra 5 e 17 anni e gruppi scolastici per bambini tra 12 e 17 anni. The [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-766","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>School - JoStudy English Academy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jostudyenglishacademy.com\/es\/school\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"School - JoStudy English Academy\" \/>\n<meta property=\"og:description\" content=\"Scuola Stai cercando un corso di inglese per bambini nel Regno Unito? Puoi scegliere un corso di inglese per bambini tra i tanti che possiamo offrire. I programmi di gruppo e in singola sono per studenti di et\u00e0 compresa tra 5 e 17 anni e gruppi scolastici per bambini tra 12 e 17 anni. The [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jostudyenglishacademy.com\/es\/school\/\" \/>\n<meta property=\"og:site_name\" content=\"JoStudy English Academy\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-29T15:08:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jostudyenglishacademy.com\/wp-content\/uploads\/2019\/11\/Lesson-Live-2-1-OK.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.jostudyenglishacademy.com\/es\/school\/\",\"url\":\"https:\/\/www.jostudyenglishacademy.com\/es\/school\/\",\"name\":\"School - JoStudy English Academy\",\"isPartOf\":{\"@id\":\"https:\/\/www.jostudyenglishacademy.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.jostudyenglishacademy.com\/es\/school\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.jostudyenglishacademy.com\/es\/school\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.jostudyenglishacademy.com\/wp-content\/uploads\/2019\/11\/Lesson-Live-2-1-OK.png\",\"datePublished\":\"2019-11-19T15:50:38+00:00\",\"dateModified\":\"2019-11-29T15:08:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.jostudyenglishacademy.com\/es\/school\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.jostudyenglishacademy.com\/es\/school\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.jostudyenglishacademy.com\/es\/school\/#primaryimage\",\"url\":\"https:\/\/www.jostudyenglishacademy.com\/wp-content\/uploads\/2019\/11\/Lesson-Live-2-1-OK.png\",\"contentUrl\":\"https:\/\/www.jostudyenglishacademy.com\/wp-content\/uploads\/2019\/11\/Lesson-Live-2-1-OK.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.jostudyenglishacademy.com\/es\/school\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.jostudyenglishacademy.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"School\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.jostudyenglishacademy.com\/#website\",\"url\":\"https:\/\/www.jostudyenglishacademy.com\/\",\"name\":\"JoStudy English Academy\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.jostudyenglishacademy.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.jostudyenglishacademy.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.jostudyenglishacademy.com\/#organization\",\"name\":\"JoStudy English Academy\",\"url\":\"https:\/\/www.jostudyenglishacademy.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.jostudyenglishacademy.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.jostudyenglishacademy.com\/wp-content\/uploads\/2025\/09\/cropped-JoStudy-Logo-2.png\",\"contentUrl\":\"https:\/\/www.jostudyenglishacademy.com\/wp-content\/uploads\/2025\/09\/cropped-JoStudy-Logo-2.png\",\"width\":1500,\"height\":499,\"caption\":\"JoStudy English Academy\"},\"image\":{\"@id\":\"https:\/\/www.jostudyenglishacademy.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"School - JoStudy English Academy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jostudyenglishacademy.com\/es\/school\/","og_locale":"es_ES","og_type":"article","og_title":"School - JoStudy English Academy","og_description":"Scuola Stai cercando un corso di inglese per bambini nel Regno Unito? Puoi scegliere un corso di inglese per bambini tra i tanti che possiamo offrire. I programmi di gruppo e in singola sono per studenti di et\u00e0 compresa tra 5 e 17 anni e gruppi scolastici per bambini tra 12 e 17 anni. The [&hellip;]","og_url":"https:\/\/www.jostudyenglishacademy.com\/es\/school\/","og_site_name":"JoStudy English Academy","article_modified_time":"2019-11-29T15:08:15+00:00","og_image":[{"url":"https:\/\/www.jostudyenglishacademy.com\/wp-content\/uploads\/2019\/11\/Lesson-Live-2-1-OK.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.jostudyenglishacademy.com\/es\/school\/","url":"https:\/\/www.jostudyenglishacademy.com\/es\/school\/","name":"School - JoStudy English Academy","isPartOf":{"@id":"https:\/\/www.jostudyenglishacademy.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jostudyenglishacademy.com\/es\/school\/#primaryimage"},"image":{"@id":"https:\/\/www.jostudyenglishacademy.com\/es\/school\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jostudyenglishacademy.com\/wp-content\/uploads\/2019\/11\/Lesson-Live-2-1-OK.png","datePublished":"2019-11-19T15:50:38+00:00","dateModified":"2019-11-29T15:08:15+00:00","breadcrumb":{"@id":"https:\/\/www.jostudyenglishacademy.com\/es\/school\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jostudyenglishacademy.com\/es\/school\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.jostudyenglishacademy.com\/es\/school\/#primaryimage","url":"https:\/\/www.jostudyenglishacademy.com\/wp-content\/uploads\/2019\/11\/Lesson-Live-2-1-OK.png","contentUrl":"https:\/\/www.jostudyenglishacademy.com\/wp-content\/uploads\/2019\/11\/Lesson-Live-2-1-OK.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jostudyenglishacademy.com\/es\/school\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jostudyenglishacademy.com\/"},{"@type":"ListItem","position":2,"name":"School"}]},{"@type":"WebSite","@id":"https:\/\/www.jostudyenglishacademy.com\/#website","url":"https:\/\/www.jostudyenglishacademy.com\/","name":"JoStudy English Academy","description":"","publisher":{"@id":"https:\/\/www.jostudyenglishacademy.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jostudyenglishacademy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.jostudyenglishacademy.com\/#organization","name":"JoStudy English Academy","url":"https:\/\/www.jostudyenglishacademy.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.jostudyenglishacademy.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.jostudyenglishacademy.com\/wp-content\/uploads\/2025\/09\/cropped-JoStudy-Logo-2.png","contentUrl":"https:\/\/www.jostudyenglishacademy.com\/wp-content\/uploads\/2025\/09\/cropped-JoStudy-Logo-2.png","width":1500,"height":499,"caption":"JoStudy English Academy"},"image":{"@id":"https:\/\/www.jostudyenglishacademy.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.jostudyenglishacademy.com\/es\/wp-json\/wp\/v2\/pages\/766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jostudyenglishacademy.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.jostudyenglishacademy.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.jostudyenglishacademy.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jostudyenglishacademy.com\/es\/wp-json\/wp\/v2\/comments?post=766"}],"version-history":[{"count":12,"href":"https:\/\/www.jostudyenglishacademy.com\/es\/wp-json\/wp\/v2\/pages\/766\/revisions"}],"predecessor-version":[{"id":889,"href":"https:\/\/www.jostudyenglishacademy.com\/es\/wp-json\/wp\/v2\/pages\/766\/revisions\/889"}],"wp:attachment":[{"href":"https:\/\/www.jostudyenglishacademy.com\/es\/wp-json\/wp\/v2\/media?parent=766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}